{"id":1046,"date":"2012-07-22T13:44:44","date_gmt":"2012-07-22T19:44:44","guid":{"rendered":"http:\/\/www.eloriente.net\/home\/?p=1046"},"modified":"2015-11-10T14:36:38","modified_gmt":"2015-11-10T20:36:38","slug":"poblacion-en-oaxaca-parte-4-migracion","status":"publish","type":"post","link":"http:\/\/www.eloriente.net\/home\/2012\/07\/22\/poblacion-en-oaxaca-parte-4-migracion\/","title":{"rendered":"Poblaci\u00f3n en Oaxaca (Parte 4) Migraci\u00f3n"},"content":{"rendered":"<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- BANNER ELORIENTE INCRUSTADO NOTAS --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 300px; height: 250px;\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"7974633627\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/p>\n<p>&nbsp;<\/p>\n<p>eloriente.net \/ INEGI<\/p>\n<p>22 de julio de 2012<\/p>\n<p>Con motivo del D\u00eda Mundial de la Poblaci\u00f3n, el Instituto Nacional de Estad\u00edstica (INEGI) en Oaxaca, prepar\u00f3 este reporte especial que comparte con los lectores de EL ORIENTE. Lo publicaremos en partes para facilitar su lectura. Revisa las entregas en este sitio. Si quieres revisar las anteriores da Click a continuaci\u00f3n<\/p>\n<p><a href=\"http:\/\/wp.me\/p2wXNd-9o\" target=\"_blank\">PARTE 1<\/a><\/p>\n<p><a href=\"http:\/\/wp.me\/p2wXNd-cB\" target=\"_blank\">PARTE 2<\/a><\/p>\n<p><a href=\"http:\/\/wp.me\/p2wXNd-er\" target=\"_blank\">PARTE 3<\/a><\/p>\n<p style=\"text-align: right;\"><strong>PARTE 4<\/strong><\/p>\n<p>\u00a0<strong>MIGRACI\u00d3N INTERNA<\/strong><\/p>\n<p>La localizaci\u00f3n de fuentes de trabajo as\u00ed como el desarrollo de infraestructura y la disponibilidad de servicios moldean la direcci\u00f3n, magnitud y composici\u00f3n demogr\u00e1fica de los diversos flujos migratorios, configurando el tama\u00f1o, crecimiento y estructura de la poblaci\u00f3n en las entidades del pa\u00eds.<\/p>\n<p>El proceso de industrializaci\u00f3n iniciado en la cuarta d\u00e9cada del siglo pasado molde\u00f3 una migraci\u00f3n interna del campo a la ciudad, aspecto que ha cedido importancia a las migraciones entre n\u00facleos urbanos y de las grandes zonas metropolitanas a ciudades de tama\u00f1o intermedio.<a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftn1\">[1]<\/a> Un estudio realizado por CONAPO se\u00f1ala que \u201cen la segunda mitad de los a\u00f1os cincuenta, s\u00f3lo en el Distrito Federal y el estado de M\u00e9xico el principal flujo inmigratorio exced\u00eda las 30 mil personas; en cambio, en 21 estados era inferior a diez mil, siendo Oaxaca una de estas entidades, e incluso, en Yucat\u00e1n, el flujo m\u00e1s grande, originado en Campeche, apenas fue de 814 individuos\u201d.<a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftn2\">[2]<\/a><\/p>\n<p style=\"text-align: left;\" align=\"center\"><strong>Principal entidad de origen de los inmigrantes interestatales<\/strong><\/p>\n<p><strong>1955-1960<\/strong><\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/principal-entidad-de-origende-inmigrantes-inegi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1048 alignleft\" title=\"principal entidad de origende inmigrantes inegi\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/principal-entidad-de-origende-inmigrantes-inegi-300x179.jpg\" alt=\"\" width=\"300\" height=\"179\" srcset=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/principal-entidad-de-origende-inmigrantes-inegi-300x179.jpg 300w, http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/principal-entidad-de-origende-inmigrantes-inegi.jpg 878w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: left;\" align=\"center\">Fuente: <strong>CONAPO<\/strong>. <em>La poblaci\u00f3n de M\u00e9xico en el nuevo siglo.<\/em><\/p>\n<p>En la actualidad la migraci\u00f3n interestata, muestra algunos rasgos que es importante destacar, de acuerdo con datos censales de 2010, en Oaxaca, 2.5% de la poblaci\u00f3n de 5 a\u00f1os y m\u00e1s, en 2005 viv\u00eda en otra (inmigraci\u00f3n reciente); la estructura por sexo de estos migrantes refleja que de cada 100 hombres que cambiaron de entidad de residencia cinco a\u00f1os antes, hay 100 mujeres que tambi\u00e9n lo hicieron.<\/p>\n<p>Otro rasgo importante de la migraci\u00f3n interna reciente es, que 66.1% de la poblaci\u00f3n de 5 a\u00f1os y m\u00e1s que cambi\u00f3 de entidad de residencia en 2005 para llegar a vivir a Oaxaca, \u00a0llegaron a residir a localidades con un tama\u00f1o de menos de 15 mil habitantes, mientras que a las ciudades peque\u00f1as (de 15 mil a 99 999 de habitantes) y medianas (de 100 000 a 499 999 habitantes), llegaron 21.9 y 11.9% de los inmigrantes recientes, respectivamente.<\/p>\n<p>El Saldo Neto Migratorio (SNM)<a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftn3\"><sup><sup>[3]<\/sup><\/sup><\/a> muestra que 13 entidades federativas pierden poblaci\u00f3n, destacando el Distrito Federal con un saldo negativo, en quinto lugar Oaxaca; mientras que en 19 estados presentan saldos positivos, siendo Baja California Sur la entidad con mayor ganancia, seguida en orden de importancia por Quintana Roo y Colima. Una visi\u00f3n m\u00e1s precisa de los desplazamientos al interior del pa\u00eds se tiene cuando se considera la migraci\u00f3n entre los municipios de una misma entidad federativa. Si se suma al 2.5% de inmigrantes interestatales, el 2.5% de personas que en 2005 se fueron a vivir de un municipio a otro de la misma entidad federativa, se tiene que en Oaxaca, 5.0% de la poblaci\u00f3n de 5 a\u00f1os y m\u00e1s cruzaron alg\u00fan limite municipal dentro o fuera de la misma entidad para cambiar su lugar de residencia.<\/p>\n<p><strong>\u00a0<\/strong><strong>Porcentaje del saldo neto migratorio seg\u00fan lugar de residencia en junio de 2005<\/strong><\/p>\n<p>(Entidades con mayor y menor SNM)<\/p>\n<p align=\"center\"><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/porcentaje-del-saldo-neto-migratorio-inegi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1049 alignleft\" title=\"porcentaje del saldo neto migratorio inegi\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/porcentaje-del-saldo-neto-migratorio-inegi-300x180.jpg\" alt=\"\" width=\"300\" height=\"180\" srcset=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/porcentaje-del-saldo-neto-migratorio-inegi-300x180.jpg 300w, http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/porcentaje-del-saldo-neto-migratorio-inegi.jpg 482w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <strong>INEGI. <\/strong>Censo de Poblaci\u00f3n y Vivienda, 2010. Tabulados b\u00e1sicos.<\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- BANNER PEQUE\u00d1O PARA ENTRENOTAS EL ORIENTE --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 468px; height: 60px;\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"4953536424\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/p>\n<p><strong>MIGRACI\u00d3N INTERNACIONAL <\/strong><\/p>\n<p>La Organizaci\u00f3n de las Naciones Unidas calcula que para 2010, el n\u00famero de migrantes internacionales lleg\u00f3 a 214 millones, representando 3.1% del total de la poblaci\u00f3n mundial, cifra que aument\u00f3 58 millones desde 1990; el 60% de ellos se dirigi\u00f3 a las regiones m\u00e1s desarrolladas, siendo los Estados Unidos de Am\u00e9rica (20 por ciento); Federaci\u00f3n Rusa (5.7%), Alemania (5.0%), Arabia Saudita (3.4%) y Canad\u00e1 (3.4%) los principales destinos.<a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftn4\">[4]<\/a><\/p>\n<p>En M\u00e9xico la migraci\u00f3n internacional es un elemento demogr\u00e1fico que tiene un inter\u00e9s creciente por su importancia econ\u00f3mica, pol\u00edtica y social; por una parte, el fen\u00f3meno migratorio entre M\u00e9xico y los Estados Unidos de Am\u00e9rica (EUA) tiene una larga tradici\u00f3n hist\u00f3rica, donde la mayor\u00eda de los desplazamientos son esencialmente laborales y por otra, se debe reconocer que nuestro territorio se ha convertido en un pa\u00eds de tr\u00e1nsito, principalmente para los migrantes centroamericanos, cuyo destino es el vecino pa\u00eds del norte. En este contexto el gobierno mexicano ha puesto mayor atenci\u00f3n a temas relacionados con los derechos humanos de los migrantes, la vinculaci\u00f3n con los mexicanos en el exterior y las remesas, entre otros que resultan importantes en la agenda p\u00fablica del gobierno federal.<a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftn5\">[5]<\/a><\/p>\n<p>Las personas nacidas en M\u00e9xico que viven en el vecino pa\u00eds del norte, han incrementado su n\u00famero desde la d\u00e9cada de los sesenta: de 260 mil en 1960 a 2.6 millones en 1990.<a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftn6\">[6]<\/a>\u00a0 Es en las \u00faltimas dos d\u00e9cadas que el n\u00famero de mexicanos residentes en EUA experimenta un crecimiento significativo, de acuerdo con la Encuesta de la Comunidad Americana (ACS, por sus siglas en ingl\u00e9s), en 2010, hay 11.9 millones de mexicanos residentes en los Estados Unidos de Am\u00e9rica, lo que en t\u00e9rminos relativos representa 3.9% del total de su poblaci\u00f3n y 28.2% del total de los migrantes. En el a\u00f1o 2000, el 46.1% de la poblaci\u00f3n nacida en M\u00e9xico residente en EUA era menor de 30 a\u00f1os, para 2010 esta poblaci\u00f3n disminuy\u00f3 a 30.9 por ciento; entre algunas explicaciones que se plantean a esta situaci\u00f3n es que los migrantes puede deberse a un aumento en el n\u00famero de j\u00f3venes que son deportados.<\/p>\n<p><strong>Estructura por edad de la poblaci\u00f3n nacida en M\u00e9xico residente en los Estados Unidos<\/strong><\/p>\n<p><strong>de Am\u00e9rica seg\u00fan sexo<\/strong><\/p>\n<p><strong>2000 y 2010<\/strong><\/p>\n<p align=\"center\"><strong><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/estructura-por-edad-de-la-poblacion-inegi-eua.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1050 alignleft\" title=\"estructura por edad de la poblacion inegi eua\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/estructura-por-edad-de-la-poblacion-inegi-eua-300x234.jpg\" alt=\"\" width=\"300\" height=\"234\" srcset=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/estructura-por-edad-de-la-poblacion-inegi-eua-300x234.jpg 300w, http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/estructura-por-edad-de-la-poblacion-inegi-eua.jpg 641w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p align=\"center\"><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Fuente: U.S. Census Bureau. Muestra Censal 5% 2000. Base de datos.<\/p>\n<p>\u00ad\u00ad\u00ad\u00ad\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 _____\u00a0 American Community Survey 2010. Base de datos.<\/p>\n<p>Para Oaxaca los datos censales de 2010 indican que la emigraci\u00f3n internacional es predominantemente masculina, de la poblaci\u00f3n que durante el periodo 2005-2010 sali\u00f3 del pa\u00eds (60 mil), cuatro de cada cinco son hombres. En cuanto a la inmigraci\u00f3n internacional, tomando en cuenta el enfoque de los nacidos en otro pa\u00eds, se observa un incremento de 1990 a 2010, pasando de 0.5 a 4.5 por cada mil nacidos en otro pa\u00eds; de acuerdo al evento censal m\u00e1s reciente, por sexo no se muestran diferencias significativas en este indicador (4.3 y 4.7 por cada mil mujeres y hombres, respectivamente), no obstante, la mayor\u00eda (88.8%) proviene de los EUA. Lo anterior puede ser un reflejo del retorno de familias desde aquel pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftnref1\">[1]<\/a> CONAPO (2001). <em>Op.cit.<\/em><\/p>\n<div>\n<div>\n<p>\u00a0<a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftnref2\">[2]<\/a> Ibid.<\/p>\n<\/div>\n<div>\n<p><a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftnref3\">[3]<\/a> \u00a0\u00a0 Es el resultado de la diferencia entre la poblaci\u00f3n inmigrante y la emigrante, en una fecha determinada.<\/p>\n<p><a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftnref4\">[4]<\/a> \u00a0\u00a0 United Nations, Department of Economic and Social Affairs, Population Division. <em>International Migration Report 2009: A global Assessment. <\/em><a href=\"http:\/\/www.un.org\/esa\/population\/publications\/migration\/WorldMigrationReport2009.pdf\">http:\/\/www.un.org\/esa\/population\/publications\/migration\/WorldMigrationReport2009.pdf<\/a>, mayo de 2012.<\/p>\n<\/div>\n<div>\n<p><em>\u00a0<\/em><a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftnref5\">[5]<\/a> \u00a0\u00a0 Canales, Alejandro. \u201cMarcos constitucionales, normativos y de pol\u00edticas sobre migraci\u00f3n internacional: el caso M\u00e9xico\u201d, en: Jorge Mart\u00ednez Pizarro (ED).<em> Migraci\u00f3n Internacional en Am\u00e9rica Latina y el Caribe. Nuevas tendencias, nuevos enfoques. <\/em><a href=\"http:\/\/www.cepal.org\/publicaciones\/xml\/4\/43634\/lcr2170.pdf\">http:\/\/www.cepal.org\/publicaciones\/xml\/4\/43634\/lcr2170.pdf<\/a>,\u00a0 mayo de 2012.<\/p>\n<\/div>\n<div>\n<p>\u00a0<a title=\"\" href=\"file:\/\/\/C:\/Users\/Juan%20Pablo\/Documents\/EL%20ORIENTE\/Oax.D%C3%8DA%20MUNDIAL%20DE%20LA%20POBLACION_2012%20oax.doc#_ftnref6\">[6]<\/a> \u00a0\u00a0\u00a0 CONAPO (2001). <em>Op.cit.<\/em><\/p>\n<\/div>\n<\/div>\n\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"http:\/\/www.eloriente.net\/home\/2012\/07\/22\/poblacion-en-oaxaca-parte-4-migracion\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t\tdata-colorscheme = \"dark\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div>\n\t\t  <style>\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>&nbsp; eloriente.net \/ INEGI 22 de julio de 2012 Con motivo del D\u00eda Mundial de la Poblaci\u00f3n, el Instituto Nacional de Estad\u00edstica (INEGI) en Oaxaca, prepar\u00f3 este reporte especial que comparte con los lectores de EL ORIENTE. Lo publicaremos en partes para facilitar su lectura. Revisa las entregas en este sitio. Si quieres revisar las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32,13,35,21],"tags":[],"class_list":["post-1046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entradas","category-especiales","category-secciones-oriente","category-politica-y-gobierno"],"jetpack_featured_media_url":"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/07\/principal-entidad-de-origende-inmigrantes-inegi.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/1046"}],"collection":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/comments?post=1046"}],"version-history":[{"count":3,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/1046\/revisions"}],"predecessor-version":[{"id":40468,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/1046\/revisions\/40468"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media\/1048"}],"wp:attachment":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media?parent=1046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/categories?post=1046"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/tags?post=1046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}