{"id":37910,"date":"2015-07-11T10:32:41","date_gmt":"2015-07-11T16:32:41","guid":{"rendered":"http:\/\/www.eloriente.net\/home\/?p=37910"},"modified":"2015-07-14T09:46:48","modified_gmt":"2015-07-14T15:46:48","slug":"abre-festival-de-poesia-de-medellin-25-anos-resistiendo-la-guerra-a-fuerza-de-poesia","status":"publish","type":"post","link":"http:\/\/www.eloriente.net\/home\/2015\/07\/11\/abre-festival-de-poesia-de-medellin-25-anos-resistiendo-la-guerra-a-fuerza-de-poesia\/","title":{"rendered":"Abre Festival de Poes\u00eda de Medell\u00edn; 25 a\u00f1os resistiendo la guerra a fuerza de poes\u00eda"},"content":{"rendered":"<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- BANNER ELORIENTE INCRUSTADO NOTAS --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 300px; height: 250px;\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"7974633627\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>eloriente.net\/Fundaci\u00f3n Right Livelihood Award<\/p>\n<p>11 de julio de 2015<\/p>\n<ul>\n<li><strong>El conflicto interno colombiano contabiliza unos cincuenta a\u00f1os. Durante la mitad de ese tiempo, ha existido un festival dispuesto a desarmarlo. <\/strong><strong>Comenz\u00f3 como una protesta contra la violencia y el terror pol\u00edtico y hoy es uno de los encuentros de poes\u00eda m\u00e1s grandes y prestigiosos del mundo.<\/strong><\/li>\n<li><strong>Mientras los di\u00e1logos de paz en La Habana atraviesan su momento m\u00e1s cr\u00edtico, Medell\u00edn los alienta dando inicio a la 25<sup>a<\/sup> edici\u00f3n del Festival Internacional de Poes\u00eda. Se estima que alrededor de 10.000 personas asistir\u00e1n ma\u00f1ana al acto inaugural en el Parque de los Deseos.<\/strong><\/li>\n<\/ul>\n<p>Donde el conflicto impuso balas y muerte, el festival propuso palabras y esperanza. As\u00ed fue copando las calles durante un cuarto de siglo, gan\u00e1ndole terreno al silencio, al miedo y a la oscuridad.<\/p>\n<p>Cuando las conversaciones que buscan cesar el fuego transitan horas \u00e1lgidas, pueblo y poetas siguen sumando palabras para que la paz deje de ser tan solo una de ellas y se torne pronto realidad palpable. \u201cEs lo que todo el pa\u00eds est\u00e1 esperando pues esta es una guerra muy larga, ya estamos muy cansados, no lleva a nada, no se acaba nunca. Toda la vida desde que \u00e9ramos ni\u00f1os son las mismas noticias tr\u00e1gicas. De ah\u00ed la fuerza que tiene el Festival y la enorme expectativa que genera en la ciudad\u201d, explica Fernando Rend\u00f3n, director del festival y uno de sus fundadores.<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2015\/07\/Festival-de-Poes\u00eda-de-medell\u00edn.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37911\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2015\/07\/Festival-de-Poes\u00eda-de-medell\u00edn.jpg\" alt=\"Festival de Poes\u00eda de medell\u00edn\" width=\"570\" height=\"449\" srcset=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2015\/07\/Festival-de-Poes\u00eda-de-medell\u00edn.jpg 570w, http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2015\/07\/Festival-de-Poes\u00eda-de-medell\u00edn-300x236.jpg 300w\" sizes=\"(max-width: 570px) 100vw, 570px\" \/><\/a><\/p>\n<p>Con la presencia de 90 poetas provenientes de 40 pa\u00edses, la vigesimo quinta edici\u00f3n del Festival Internacional de Poes\u00eda de Medell\u00edn tendr\u00e1 lugar entre el 11 y el 18 de julio. \u201cEs una programaci\u00f3n compleja, intrincada y completa que pienso le va a dar a la ciudad una atm\u00f3sfera propicia para la preservaci\u00f3n de los di\u00e1logos de paz\u201d.<\/p>\n<p>Entre conciertos de m\u00fasica, obras teatrales, muestras fotogr\u00e1ficas, funciones de t\u00edteres, proyecciones de video y conferencias, son 178 los actos de acceso libre y gratuito programados en Medell\u00edn, \u201cuna ciudad que tambi\u00e9n sufre muchos fen\u00f3menos de violencia, barrios paramilitarizados y condiciones de adversidad muy pronunciadas para el pueblo. Por eso pensamos que el festival va a fortalecer el \u00e1nimo de la comunidad, que va a afianzar la vocaci\u00f3n de paz y de vida entre la gente m\u00e1s sencilla. Eso nos llena de alegr\u00eda y de ilusi\u00f3n.La inminencia de la fiesta nos alienta\u201d.<\/p>\n<p><strong>Pueblo poeta<\/strong><\/p>\n<p>\u201cAlma. Fuego. Belleza. Transformaci\u00f3n. Esperanza. Vida. Liberaci\u00f3n. Juro que no hay nada repetido. Es asombroso, muy impresionante. Todos lo expresan de manera diferente\u201d, dice Rend\u00f3n acerca de las respuestas que dieron los habitantes de Medell\u00edn al pedirles que definan en una sola palabra el significado del festival para la ciudad y de la poes\u00eda para sus vidas.<\/p>\n<p>\u201cEs un p\u00fablico muy evolucionado, lo que a m\u00ed me da la esperanza de estar frente a una generaci\u00f3n para la paz. Tienen una alta comprensi\u00f3n de la escritura y gran desarrollo del lenguaje. Son muy lectores, mucha gente incluso escribe y env\u00eda sus poemas para los cert\u00e1menes que convocamos\u201d.<\/p>\n<p>El Festival form\u00f3 a su propio auditorio. \u201cHemos sido parte de una educaci\u00f3n no formal, una educaci\u00f3n espiritual. Yo creo que todas esas voces en conjunci\u00f3n durante tantos a\u00f1os tienen que haber producido un escalamiento en la conciencia de la gente, una transformaci\u00f3n todav\u00eda intangible pero que en alg\u00fan momento se va a expresar, se va a mostrar, se va a hacer s\u00f3lida. El futuro de Colombia va a ser muy bello porque la mayor riqueza del pa\u00eds es su pueblo\u201d.<\/p>\n<p><strong>Caminar el sue\u00f1o<\/strong><\/p>\n<p>A principios de 1990, Medell\u00edn estaba gobernada por el miedo, el terror pol\u00edtico y los enfrentamientos entre grupos armados. Unas 100 personas pod\u00edan ser asesinadas un fin de semana. Despu\u00e9s de las 8 pm, la ciudad sol\u00eda estar muerta debido a un toque de queda impuesto por los paramilitares, a\u00fan activos en el pa\u00eds.<\/p>\n<p>En ese contexto, la propuesta era simple: mediante la lectura de poes\u00eda en las calles, los promotores del Festival estimulaban a las personas a restablecer una vida cultural y reclamar su ciudad. Desde 1991, los responsables de la Revista Prometeo organizaron anualmente el Festival de Poes\u00eda recitando en calles, parques, zonas residenciales, universidades y bibliotecas, teatros, cooperativas, escuelas y centros culturales, restaurantes, centros comerciales, estaciones de metro, f\u00e1bricas, iglesias y hasta c\u00e1rceles. A lo largo de estos 25 a\u00f1os, m\u00e1s de mil poetas de 165 pa\u00edses han pasado por estos escenarios de Medell\u00edn, hablando con p\u00fablicos de todas las edades y en decenas de lenguas. Hasta 200.000 personas llegan a participar en cada edici\u00f3n del Festival.<\/p>\n<p>\u00abPor demostrar c\u00f3mo la creatividad, la belleza, la libre expresi\u00f3n y la comunidad pueden florecer y superar el miedo incluso en medio de la violencia profundamente arraigada\u00bb, en el a\u00f1o 2006 el Festival Internacional de Poes\u00eda de Medell\u00edn fue galardonado con el Right Livelihood Award, distinci\u00f3n m\u00e1s conocida como Premio Nobel Alternativo, que cada fin de a\u00f1o se entrega en el Parlamento Sueco. Tres a\u00f1os despu\u00e9s se sancion\u00f3 en Colombia la ley que declar\u00f3 al Festival como Patrimonio Cultural de la Naci\u00f3n.<\/p>\n<p>\u201cAhora es m\u00e1s posible ver hacia el futuro que lo que nosotros pod\u00edamos ver al principio\u201d, reflexiona Rend\u00f3n. \u201cPara nada pod\u00edamos imaginar todo esto. Ten\u00edamos solo un sue\u00f1o, pero muy informe, indefinido. Sin embargo, caminando sin saber a d\u00f3nde ir, caminamos con tanta fuerza como si lo supi\u00e9ramos. \u00a1Y mira d\u00f3nde estamos!\u201d.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/5wT_s5Wh_NQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"twitter-tweet\" lang=\"es\">\n<p dir=\"ltr\" lang=\"es\">\u00c9sta es la forma en que miras a la gente en el tren para luego extra\u00f1arla. <a href=\"https:\/\/twitter.com\/hashtag\/25FIPM?src=hash\">#25FIPM<\/a> Robin Myers <a href=\"http:\/\/t.co\/Ocx357GlyW\">http:\/\/t.co\/Ocx357GlyW<\/a> <a href=\"http:\/\/t.co\/U4hyznCF6c\">pic.twitter.com\/U4hyznCF6c<\/a><\/p>\n<p>\u2014 Corporaci\u00f3n Prometeo (@poesiamedellin) <a href=\"https:\/\/twitter.com\/poesiamedellin\/status\/618854910210256896\">julio 8, 2015<\/a><\/p><\/blockquote>\n<p><script src=\"\/\/platform.twitter.com\/widgets.js\" async=\"\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>OTRAS ENTRADAS:<\/strong><\/p>\n<div class=\"featuredpost\">\n<h2 class=\"posttitle bigposttitle\"><a title=\"Enlace Permanente a La Brecha Digital en Oaxaca, por Diego Gonz\u00e1lez\" href=\"http:\/\/www.eloriente.net\/home\/2015\/07\/09\/la-brecha-digital-en-oaxaca-por-diego-gonzalez\/\" rel=\"bookmark\">La Brecha Digital en Oaxaca, por Diego Gonz\u00e1lez<\/a><\/h2>\n<p>Las nuevas tecnolog\u00edas son herramientas que nos maravillan cada d\u00eda y que suelen hacernos la vida m\u00e1s f\u00e1cil, sin\u2026<\/p>\n<p class=\"postmeta\"><span class=\"meta_date\">julio 9, 2015<\/span><\/p>\n<div class=\"toolbar-social\">\n<div class=\"social-widget\">\n<div id=\"sharing-widget\"><a class=\"button icon-share\">Compartir<\/a><span class=\"share-count\">7<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"featuredpost\">\n<p><a href=\"http:\/\/www.eloriente.net\/home\/2015\/07\/09\/oaxaca-un-continente-que-hacemos-para-preservar-nuestra-herencia-cultural-y-natural\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"alignleft\" title=\"Oaxaca, un Continente: \u00bfQu\u00e9 hacemos para preservar nuestra herencia cultural y natural?\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/themes\/city-desk\/timthumb.php?src=http%3A%2F%2Fwww.eloriente.net%2Fhome%2Fwp-content%2Fuploads%2F2014%2F09%2FHuatulco-Daniel-Lobo1.jpg&amp;q=90&amp;w=90&amp;h=83&amp;zc=1\" alt=\"Oaxaca, un Continente: \u00bfQu\u00e9 hacemos para preservar nuestra herencia cultural y natural?\" \/><\/a><\/p>\n<h2 class=\"posttitle \"><a title=\"Enlace Permanente a Oaxaca, un Continente: \u00bfQu\u00e9 hacemos para preservar nuestra herencia cultural y natural?\" href=\"http:\/\/www.eloriente.net\/home\/2015\/07\/09\/oaxaca-un-continente-que-hacemos-para-preservar-nuestra-herencia-cultural-y-natural\/\" rel=\"bookmark\">Oaxaca, un Continente: \u00bfQu\u00e9 hacemos para preservar nuestra herencia cultural y natural?<\/a><\/h2>\n<p>(www.eloriente.net, M\u00e9xico, 9 de julio de 2015. Por: \u00c1ngel Osorio @senderosoax).- Oaxaca, sin duda, es uno de los lugares\u2026<\/p>\n<p class=\"postmeta\"><span class=\"meta_date\">julio 9, 2015<\/span><\/p>\n<div class=\"toolbar-social\">\n<div class=\"social-widget\">\n<div id=\"sharing-widget\"><a class=\"button icon-share\">Compartir<\/a><span class=\"share-count\">11<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"featuredpost\">\n<p><a href=\"http:\/\/www.eloriente.net\/home\/2015\/07\/06\/litigantes-en-oaxaca-recibiran-notificaciones-via-token\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"alignleft\" title=\"Litigantes en Oaxaca recibir\u00e1n notificaciones v\u00eda \u2018token\u2019\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/themes\/city-desk\/timthumb.php?src=http%3A%2F%2Fwww.eloriente.net%2Fhome%2Fwp-content%2Fuploads%2F2015%2F07%2FEntr%C3%B3-en-funcionamiento-la-Central-de-Actuarios-del-Poder-Judicial.jpg&amp;q=90&amp;w=90&amp;h=83&amp;zc=1\" alt=\"Litigantes en Oaxaca recibir\u00e1n notificaciones v\u00eda \u2018token\u2019\" \/><\/a><\/p>\n<h2 class=\"posttitle \"><a title=\"Enlace Permanente a Litigantes en Oaxaca recibir\u00e1n notificaciones v\u00eda \u2018token\u2019\" href=\"http:\/\/www.eloriente.net\/home\/2015\/07\/06\/litigantes-en-oaxaca-recibiran-notificaciones-via-token\/\" rel=\"bookmark\">Litigantes en Oaxaca recibir\u00e1n notificaciones v\u00eda \u2018token\u2019<\/a><\/h2>\n<p>eloriente.net\/TSJEO 6 de julio de 2015 El titular del Poder Judicial de Oaxaca, magistrado Alfredo Rodrigo Lagunas\u2026<\/p>\n<p class=\"postmeta\"><span class=\"meta_date\">julio 6, 2015<\/span><\/p>\n<\/div>\n\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"http:\/\/www.eloriente.net\/home\/2015\/07\/11\/abre-festival-de-poesia-de-medellin-25-anos-resistiendo-la-guerra-a-fuerza-de-poesia\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t\tdata-colorscheme = \"dark\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div>\n\t\t  <style>\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; eloriente.net\/Fundaci\u00f3n Right Livelihood Award 11 de julio de 2015 El conflicto interno colombiano contabiliza unos cincuenta a\u00f1os. Durante la mitad de ese tiempo, ha existido un festival dispuesto a desarmarlo. Comenz\u00f3 como una protesta contra la violencia y el terror pol\u00edtico y hoy es uno de los encuentros de poes\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32,13,10,24,31],"tags":[3824,3823,383],"class_list":["post-37910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entradas","category-especiales","category-lo-mas-reciente","category-mexico-y-el-mundo","category-principal","tag-festival-de-poesia-de-medellin","tag-medellin","tag-poesia"],"jetpack_featured_media_url":"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2015\/07\/Festival-de-Poes\u00eda-de-medell\u00edn.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/37910"}],"collection":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/comments?post=37910"}],"version-history":[{"count":3,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/37910\/revisions"}],"predecessor-version":[{"id":37950,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/37910\/revisions\/37950"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media\/37911"}],"wp:attachment":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media?parent=37910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/categories?post=37910"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/tags?post=37910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}