{"id":42614,"date":"2016-03-05T12:39:24","date_gmt":"2016-03-05T18:39:24","guid":{"rendered":"http:\/\/www.eloriente.net\/home\/?p=42614"},"modified":"2016-03-05T12:39:24","modified_gmt":"2016-03-05T18:39:24","slug":"oaxaca-maestria-en-sociologia-uabjo-es-posgrado-de-calidad-eduardo-bautista","status":"publish","type":"post","link":"http:\/\/www.eloriente.net\/home\/2016\/03\/05\/oaxaca-maestria-en-sociologia-uabjo-es-posgrado-de-calidad-eduardo-bautista\/","title":{"rendered":"OAXACA: Maestr\u00eda en Sociolog\u00eda UABJO es posgrado de calidad: Eduardo Bautista"},"content":{"rendered":"<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- BANNER ELORIENTE INCRUSTADO NOTAS --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 300px; height: 250px;\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"7974633627\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><br \/>\neloriente.net\/UABJO<\/p>\n<p>5 de marzo de 2016<\/p>\n<p>En apego a lo dispuesto por la Ley Org\u00e1nica de la Universidad Aut\u00f3noma \u201cBenito Ju\u00e1rez\u201d de Oaxaca (UABJO), el Director del Instituto de Investigaciones Sociol\u00f3gicas (IISUABJO), Eduardo Carlos Bautista Mart\u00ednez, present\u00f3 ante integrantes del Consejo T\u00e9cnico, el Rector, Eduardo Mart\u00ednez Helmes y la comunidad universitaria el informe acad\u00e9mico \u2013 administrativo correspondiente al primer a\u00f1o de su gesti\u00f3n.<\/p>\n<p>Bautista Mart\u00ednez se\u00f1al\u00f3 que el trabajo realizado durante este primer a\u00f1o es producto del empe\u00f1o de todas las \u00e1reas que se enfocaron en cumplir los objetivos y metas espec\u00edficas que contribuyen al desarrollo de una instituci\u00f3n educativa que se coloca como una de las m\u00e1s productivas en t\u00e9rminos de investigaci\u00f3n, docencia y vinculaci\u00f3n de nivel superior en el estado.<\/p>\n<p>\u201cLos logros y alcances prueban el empe\u00f1o que realizamos los universitarios, as\u00ed como nuestro compromiso por impulsar el desarrollo del IISUABJO, con apego a los principios que nos rigen y que fundamentan el deber ser de nuestra alma mater, la M\u00e1xima Casa de Estudios en el estado\u201d.<\/p>\n<p>En lo referente a la docencia, el funcionario universitario se\u00f1al\u00f3 que actualmente 3 de los 5 programas de licenciatura generacionales con que cuenta el Instituto, cuentan con reconocimiento de calidad por la Asociaci\u00f3n para la Acreditaci\u00f3n y Certificaci\u00f3n en Ciencias Sociales (ACCECISO), con vigencia a 2020. De igual manera, el programa de Maestr\u00eda en Sociolog\u00eda cuenta con reconocimiento en el Programa de Nacional de Posgrados de Calidad (PNPC-CONACYT) con vigencia al 2016.<\/p>\n<p>Por otra parte, en el tema de investigaci\u00f3n, al d\u00eda de hoy se cuenta con una planta acad\u00e9mica formada por 11 profesores de tiempo completo; 9 con nivel de doctorado, 8 con perfil deseable PRODEP-SEP y 6 con reconocimiento del Sistema Nacional de Investigadores CONACYT.<br \/>\n<script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- BANNER PEQUE\u00d1O PARA ENTRENOTAS EL ORIENTE --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 468px; height: 60px;\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"4953536424\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><br \/>\nDe igual manera, el Instituto cuenta con tres Cuerpos Acad\u00e9micos : G\u00e9nero, Cultura y Desarrollo (consolidado), Estudios Pol\u00edticos (en consolidaci\u00f3n) y Estudios sobre la Sociedad Rural (en consolidaci\u00f3n), con las siguientes l\u00edneas de investigaci\u00f3n: Significados culturales, sentidos locales e impactos sociales de desarrollo; Identidad, g\u00e9nero y poder en los espacios urbanos rurales; la dimensi\u00f3n sociocultural de la producci\u00f3n y la circulaci\u00f3n de productos; Sociedad rural y globalizaci\u00f3n; Estructura de Poder y movimientos sociales; Elecciones y gobernabilidad y Pol\u00edticas p\u00fablicas.<\/p>\n<p>Entre algunos de los logros destacados en materia de vinculaci\u00f3n, se\u00f1al\u00f3 la participaci\u00f3n en redes nacionales e internacionales como el Consejo Latinoamericano de Ciencias sociales de Am\u00e9rica Latina y el Caribe (CLACSO) y el Consejo Mexicano de Ciencias sociales (COMECSO). En este sentido, destac\u00f3 la vinculaci\u00f3n con el COMECSO para la edici\u00f3n conjunta del Tablero Sociol\u00f3gico, el cual se ha posicionado como el principal \u00f3rgano de difusi\u00f3n de actividades acad\u00e9micas de publicaci\u00f3n electr\u00f3nica semanal.<\/p>\n<p>Al concluir el acto, Eduardo Mart\u00ednez Helmes, se\u00f1al\u00f3 que el impacto positivo de las acciones realizadas es notorio, y perfila al IISUABJO como una de las instituciones m\u00e1s importantes de la universidad, pues en ella se realizan acciones encaminadas a detectar y solucionar los problemas que enfrenta nuestro estado y nuestra naci\u00f3n.<\/p>\n<p>\u201cEstoy convencido de que esta unidad acad\u00e9mica, cumple con su objetivo de formar profesionales capaces de comprenderlas condiciones hist\u00f3ricas, econ\u00f3micas, pol\u00edticas y culturales actuales, para analizar y transformar, desde una visi\u00f3n racional, sistem\u00e1tica, cr\u00edtica y propositiva las pr\u00e1cticas, valores y relaciones sociales que predominan, tanto en M\u00e9xico, como en su entorno mundial\u201d.<\/p>\n<p>Finalmente, Mart\u00ednez Helmes se\u00f1al\u00f3 que en el aspecto interno, el Instituto ha destacado por su disciplina y por la formaci\u00f3n y actualizaci\u00f3n de su personal docente. Igualmente, dijo, \u201cse ha caracterizado por su diversidad de pensamiento y respeto a las ideas, lo que permite tener una apertura a las distintas corrientes de pensamiento que forman a esta universidad y a nuestra sociedad\u201d.<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/03\/Informe-director-IISUABJO.jpg\" rel=\"attachment wp-att-42615\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-42615\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/03\/Informe-director-IISUABJO-1024x683.jpg\" alt=\"Informe director IISUABJO\" width=\"504\" height=\"336\" srcset=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/03\/Informe-director-IISUABJO-1024x683.jpg 1024w, http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/03\/Informe-director-IISUABJO-300x200.jpg 300w, http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/03\/Informe-director-IISUABJO-768x512.jpg 768w\" sizes=\"(max-width: 504px) 100vw, 504px\" \/><\/a><\/p>\n<p>OTRAS ENTRADAS:<\/p>\n<h2 class=\"entry_title\"><a title=\"Enlace Permanente a OAXACA: Expertos en imagen se re\u00fanen por Fundaci\u00f3n UABJO\" href=\"http:\/\/www.eloriente.net\/home\/2016\/03\/01\/oaxaca-expertos-en-imagen-se-reunen-por-fundacion-uabjo\/\" rel=\"bookmark\">OAXACA: Expertos en imagen se re\u00fanen por Fundaci\u00f3n UABJO<\/a><\/h2>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/2016\/03\/01\/oaxaca-expertos-en-imagen-se-reunen-por-fundacion-uabjo\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"alignleft\" title=\"OAXACA: Expertos en imagen se re\u00fanen por Fundaci\u00f3n UABJO\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/themes\/city-desk\/timthumb.php?src=http%3A%2F%2Fwww.eloriente.net%2Fhome%2Fwp-content%2Fuploads%2F2016%2F03%2FIMG_8688.jpg&amp;q=90&amp;w=160&amp;h=106&amp;zc=1\" alt=\"OAXACA: Expertos en imagen se re\u00fanen por Fundaci\u00f3n UABJO\" \/><\/a><\/p>\n<p>(www.eloriente.net, M\u00e9xico, a 1 de marzo de 2016, por Valery L\u00f3pez).- La carta de presentaci\u00f3n de cualquier persona e instituci\u00f3n es su imagen, de ah\u00ed la importancia de conocer las estrategias para saber como generar la imagen correcta de acuerdo a nuestros objetivos. Conscientes de que en Oaxaca es de vital importancia generar una\u00a0visi\u00f3n [\u2026]<\/p>\n<p class=\"postmeta\"><span class=\"meta_date\">marzo 1, 2016<\/span><\/p>\n\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"http:\/\/www.eloriente.net\/home\/2016\/03\/05\/oaxaca-maestria-en-sociologia-uabjo-es-posgrado-de-calidad-eduardo-bautista\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t\tdata-colorscheme = \"dark\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div>\n\t\t  <style>\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>eloriente.net\/UABJO 5 de marzo de 2016 En apego a lo dispuesto por la Ley Org\u00e1nica de la Universidad Aut\u00f3noma \u201cBenito Ju\u00e1rez\u201d de Oaxaca (UABJO), el Director del Instituto de Investigaciones Sociol\u00f3gicas (IISUABJO), Eduardo Carlos Bautista Mart\u00ednez, present\u00f3 ante integrantes del Consejo T\u00e9cnico, el Rector, Eduardo Mart\u00ednez Helmes y la comunidad universitaria el informe acad\u00e9mico \u2013 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[29,1588,32,63,464],"tags":[6115,6116,3946,6117],"class_list":["post-42614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capital","category-comunicados-y-boletines","category-entradas","category-estados","category-oaxaca-estados","tag-maestria-en-sociologia-uabjo","tag-oaxaca-estudios-universitarios","tag-uabjo-oaxaca","tag-uabjo-posgrados-de-calidad"],"jetpack_featured_media_url":"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/03\/Informe-director-IISUABJO.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/42614"}],"collection":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/comments?post=42614"}],"version-history":[{"count":1,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/42614\/revisions"}],"predecessor-version":[{"id":42616,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/42614\/revisions\/42616"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media\/42615"}],"wp:attachment":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media?parent=42614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/categories?post=42614"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/tags?post=42614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}