{"id":49846,"date":"2017-08-22T19:32:47","date_gmt":"2017-08-23T01:32:47","guid":{"rendered":"http:\/\/www.eloriente.net\/home\/?p=49846"},"modified":"2017-08-22T17:41:54","modified_gmt":"2017-08-22T23:41:54","slug":"videocolumna-desperdicio-programa-especial-concurrente-karina-baron","status":"publish","type":"post","link":"http:\/\/www.eloriente.net\/home\/2017\/08\/22\/videocolumna-desperdicio-programa-especial-concurrente-karina-baron\/","title":{"rendered":"VIDEOCOLUMNA: El desperdicio en el Programa Especial Concurrente. Por Karina Bar\u00f3n"},"content":{"rendered":"<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- BANNER ELORIENTE INCRUSTADO NOTAS --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 300px; height: 250px;\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"7974633627\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/p>\n<p>&nbsp;<\/p>\n<p>eloriente.net<\/p>\n<p>22 de agosto de 2017<\/p>\n<p>\u00ab30 mil millones de pesos son muchos millones de pesos. Para tener una idea: es casi el doble de todo el presupuesto de egresos del estado de Colima para 2017.<\/p>\n<p>Es mucho\u2026 para andarlo desperdiciando o desaprovechando. Pero lo que es peor, \u00bfqu\u00e9 pensar\u00edas si el desperdicio se diera en \u00e1reas tan sensibles como la salud o el derecho a la alimentaci\u00f3n?\u00bb<\/p>\n<p>En su nueva videocolumna Karina Bar\u00f3n\u200b nos explica qu\u00e9 es lo que est\u00e1 sucediendo con el Programa Especial Concurrente.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2F443535572345554%2Fvideos%2F1660521303980302%2F&amp;show_text=0&amp;width=560\" width=\"560\" height=\"315\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- BANNER PEQUE\u00d1O PARA ENTRENOTAS EL ORIENTE --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 468px; height: 60px;\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"4953536424\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/p>\n<p>Karina Bar\u00f3n es Licenciada en Derecho por la Universidad Aut\u00f3noma Benito Ju\u00e1rez de Oaxaca, fue dirigente nacional de la Uni\u00f3n General Obrero, Campesina y Popular A.C. (UGOCP), integrante de la Coordinaci\u00f3n Estatal de Nueva Izquierda en Oaxaca.<\/p>\n<p>Actualmente es integrante de la Comisi\u00f3n de Agricultura y Sistemas de Riego, Secretaria de las comisiones de Desarrollo Social y Asuntos Frontera Sur-Sureste, y Presidenta de la Comisi\u00f3n de seguimiento al Programa Especial Concurrente Anexo 11.1\u00a0en la C\u00e1mara de Diputados.<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2017\/08\/KARINA-BARO\u0301N-22-DE-AGOSTO-2017.jpg\" rel=\"attachment wp-att-49847\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-49847\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2017\/08\/KARINA-BARO\u0301N-22-DE-AGOSTO-2017-1024x576.jpg\" alt=\"KARINA BARO\u0301N 22 DE AGOSTO 2017\" width=\"601\" height=\"338\" srcset=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2017\/08\/KARINA-BARO\u0301N-22-DE-AGOSTO-2017-1024x576.jpg 1024w, http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2017\/08\/KARINA-BARO\u0301N-22-DE-AGOSTO-2017-300x169.jpg 300w, http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2017\/08\/KARINA-BARO\u0301N-22-DE-AGOSTO-2017-768x432.jpg 768w, http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2017\/08\/KARINA-BARO\u0301N-22-DE-AGOSTO-2017.jpg 1920w\" sizes=\"(max-width: 601px) 100vw, 601px\" \/><\/a><\/p>\n<p><strong>OTRAS VIDEOCOLUMNAS<\/strong><\/p>\n<div id=\"post-49780\" class=\"entry loop-default border_bottom_30 post-49780 post type-post status-publish format-standard has-post-thumbnail hentry category-educacion-y-cultura category-entradas category-estados category-juan-antonio-gomez category-oaxaca-estados category-turismo-y-negocios category-videoblogs tag-calidad tag-calidad-en-el-oriente tag-el-oriente tag-juan-antonio-gomez tag-turismo tag-videocolumna\">\n<h2 class=\"entry_title\"><a title=\"Enlace Permanente a VIDEOCOLUMNA: Calidad en el turismo. Por Juan Antonio G\u00f3mez\" href=\"http:\/\/www.eloriente.net\/home\/2017\/08\/21\/videocolumna-calidad-turismo-juan-antonio-gomez\/\" rel=\"bookmark\">VIDEOCOLUMNA: Calidad en el turismo. Por Juan Antonio G\u00f3mez<\/a><\/h2>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/2017\/08\/21\/videocolumna-calidad-turismo-juan-antonio-gomez\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"alignleft\" title=\"VIDEOCOLUMNA: Calidad en el turismo. Por Juan Antonio G\u00f3mez\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/themes\/city-desk\/timthumb.php?src=http%3A%2F%2Fwww.eloriente.net%2Fhome%2Fwp-content%2Fuploads%2F2017%2F08%2FJUAN-ANTONIO-GO%CC%81MEZ-18-DE-AGOSTO-2017.jpg&amp;q=90&amp;w=160&amp;h=106&amp;zc=1\" alt=\"VIDEOCOLUMNA: Calidad en el turismo. Por Juan Antonio G\u00f3mez\" \/><\/a>\u00a0 eloriente.net 20 de agosto de 2017 \u201cDentro de la econom\u00eda del pa\u00eds, el turismo juega un papel relevante, es un importante generador de empleo y un sector atractivo para la inversi\u00f3n nacional y extranjera; por ello al igual que cualquier otra actividad productiva, debiese tener como propia una cultura de calidad reflejada en normas [\u2026]<\/p>\n<p class=\"postmeta\"><span class=\"meta_date\">agosto 21, 2017<\/span><\/p>\n<\/div>\n<div id=\"post-49785\" class=\"entry loop-default border_bottom_30 post-49785 post type-post status-publish format-standard has-post-thumbnail hentry category-viernesdefelicidad category-educacion-y-cultura category-entradas category-salud-y-estilo-de-vida category-lo-mas-reciente category-ursula-woolrich category-videoblogs tag-admiracion tag-bienestar tag-el-oriente tag-relacion-de-pareja tag-relaciones tag-ursula-woolrich tag-videoolumna\">\n<h2 class=\"entry_title\"><a title=\"Enlace Permanente a VIDEOCOLUMNA: Regalarse la admiraci\u00f3n (Parte 1). Por \u00darsula Woolrich\" href=\"http:\/\/www.eloriente.net\/home\/2017\/08\/18\/videocolumna-regalarse-la-admiracion-parte-1-ursula-woolrich\/\" rel=\"bookmark\">VIDEOCOLUMNA: Regalarse la admiraci\u00f3n (Parte 1). Por \u00darsula Woolrich<\/a><\/h2>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/2017\/08\/18\/videocolumna-regalarse-la-admiracion-parte-1-ursula-woolrich\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"alignleft\" title=\"VIDEOCOLUMNA: Regalarse la admiraci\u00f3n (Parte 1). Por \u00darsula Woolrich\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/themes\/city-desk\/timthumb.php?src=http%3A%2F%2Fwww.eloriente.net%2Fhome%2Fwp-content%2Fuploads%2F2017%2F08%2FU%CC%81RSULA-WOOLRICH-18-DE-AGOSTO-2017.jpg&amp;q=90&amp;w=160&amp;h=106&amp;zc=1\" alt=\"VIDEOCOLUMNA: Regalarse la admiraci\u00f3n (Parte 1). Por \u00darsula Woolrich\" \/><\/a>\u00a0 eloriente.net 18 de agosto de 2017 Esta semana\u00a0Ursula Woolrich\u00a0comienza el tema \u201cRegalarse la admiraci\u00f3n\u201d del libro \u201cEl amor inteligente en la vida de pareja de Battista Borsato. En la videocolumna nos habla de la admiraci\u00f3n como parte fundamental de toda relaci\u00f3n de pareja. \u00darsula Woolrich es Psic\u00f3loga con estudios de maestr\u00eda en educaci\u00f3n superior. [\u2026]<\/p>\n<p class=\"postmeta\"><span class=\"meta_date\">agosto 18, 2017<\/span><\/p>\n<\/div>\n<h2 class=\"entry_title\"><a title=\"Enlace Permanente a VIDEOCOLUMNA: \u00bfC\u00f3mo debemos construir una naci\u00f3n? Por Gerardo Castellanos\" href=\"http:\/\/www.eloriente.net\/home\/2017\/08\/16\/videocolumna-debemos-construir-una-nacion-gerardo-castellanos\/\" rel=\"bookmark\">VIDEOCOLUMNA: \u00bfC\u00f3mo debemos construir una naci\u00f3n? Por Gerardo Castellanos<\/a><\/h2>\n<p class=\"postmeta\"><a href=\"http:\/\/www.eloriente.net\/home\/2017\/08\/16\/videocolumna-debemos-construir-una-nacion-gerardo-castellanos\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"alignleft\" title=\"VIDEOCOLUMNA: \u00bfC\u00f3mo debemos construir una naci\u00f3n? Por Gerardo Castellanos\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/themes\/city-desk\/timthumb.php?src=http%3A%2F%2Fwww.eloriente.net%2Fhome%2Fwp-content%2Fuploads%2F2017%2F08%2FGERARDO-CASTELLANOS-15-DE-AGOSTO-2017.jpg&amp;q=90&amp;w=160&amp;h=106&amp;zc=1\" alt=\"VIDEOCOLUMNA: \u00bfC\u00f3mo debemos construir una naci\u00f3n? Por Gerardo Castellanos\" \/><\/a><\/p>\n<p>\u00a0 eloriente.net 16 de agosto de 2017 \u201cPara construir una naci\u00f3n debemos dar individualmente lo mejor de nosotros mismos a la persona que tenemos enfrente\u2026\u201d Esta semana\u00a0Gerardo Felipe Castellanos\u00a0hace una reflexi\u00f3n sobre lo que se necesita para construir una naci\u00f3n, y la importancia de la misma. Gerardo Castellanos es ensayista y estudioso de la historia [\u2026]<\/p>\n<p class=\"postmeta\"><span class=\"meta_date\">agosto 16, 2017<\/span><\/p>\n\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"http:\/\/www.eloriente.net\/home\/2017\/08\/22\/videocolumna-desperdicio-programa-especial-concurrente-karina-baron\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t\tdata-colorscheme = \"dark\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div>\n\t\t  <style>\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>&nbsp; eloriente.net 22 de agosto de 2017 \u00ab30 mil millones de pesos son muchos millones de pesos. Para tener una idea: es casi el doble de todo el presupuesto de egresos del estado de Colima para 2017. Es mucho\u2026 para andarlo desperdiciando o desaprovechando. Pero lo que es peor, \u00bfqu\u00e9 pensar\u00edas si el desperdicio se [&hellip;]<\/p>\n","protected":false},"author":44,"featured_media":49847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[91,32,6324,10,21,98],"tags":[477,4418,197,231,7947,6224],"class_list":["post-49846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-congreso-y-justicia","category-entradas","category-karina-baron","category-lo-mas-reciente","category-politica-y-gobierno","category-videoblogs","tag-el-oriente","tag-karina-baron","tag-opinion","tag-politica","tag-programa-especial-concurrente","tag-videocolumna"],"jetpack_featured_media_url":"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2017\/08\/KARINA-BARO\u0301N-22-DE-AGOSTO-2017.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/49846"}],"collection":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/comments?post=49846"}],"version-history":[{"count":1,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/49846\/revisions"}],"predecessor-version":[{"id":49848,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/49846\/revisions\/49848"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media\/49847"}],"wp:attachment":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media?parent=49846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/categories?post=49846"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/tags?post=49846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}