{"id":64331,"date":"2021-05-03T07:52:55","date_gmt":"2021-05-03T13:52:55","guid":{"rendered":"http:\/\/www.eloriente.net\/home\/?p=64331"},"modified":"2021-05-03T08:13:51","modified_gmt":"2021-05-03T14:13:51","slug":"indicio-esmeralda-por-jarumy-mendez","status":"publish","type":"post","link":"http:\/\/www.eloriente.net\/home\/2021\/05\/03\/indicio-esmeralda-por-jarumy-mendez\/","title":{"rendered":"Indicio Esmeralda, por Jarumy M\u00e9ndez"},"content":{"rendered":"<h4 style=\"text-align: right;\">Indicio Esmeralda, por Jarumy M\u00e9ndez<\/h4>\n<p style=\"text-align: center;\"><strong>El Debate Electoral sobre Medio Ambiente<\/strong><\/p>\n<p>El pasado 26 de abril se llev\u00f3 a cabo el Tercer Debate ante el INE de los partidos pol\u00edticos nacionales en torno al tema de Medio Ambiente y Desarrollo Sustentable. Estos formatos que ha emprendido el INE tienen como objetivo poner a \u201cDebate las plataformas electorales\u201d.<\/p>\n<p>M\u00e1s que una obligaci\u00f3n establecida en el inciso J del art\u00edculo 25 de la Ley General de Partidos Pol\u00edticos, las plataformas electorales son propuestas de car\u00e1cter pol\u00edtico, econ\u00f3mico y social que se desprenden de sus declaraciones de principios y descritas en sus programas de acci\u00f3n. En palabras del consejero electoral Cyro Murayama Rendon \u201ces lo que distingue a un partido pol\u00edtico de una mera agencia de colocaci\u00f3n de candidaturas es su consistencia y solidez program\u00e1tica\u201d.<\/p>\n<p>De ah\u00ed que el ideal sea que la ciudadan\u00eda rompiera el desencanto por los partidos pol\u00edticos y conociera las plataformas y sus diferencias, m\u00e1s que los atributos o defectos de uno u otro candidato o candidata para emitir un voto informado.<\/p>\n<p>Lo que sucede en la realidad democr\u00e1tica es que la ciudadan\u00eda se encuentra con campa\u00f1as llenas de spots, publicidad y slogans cuyas \u00fanicas diferencias son el color sin una visi\u00f3n clara y profunda del pa\u00eds que se busca gobernar; la ciudadan\u00eda desconoce c\u00f3mo se integran las plataformas electorales, los militantes desconocen su proceso de creaci\u00f3n y contenido pese a que deber\u00edan ser los manifiestos ideol\u00f3gicos que amalgaman a la militancia producto de un ejercicio participativo de \u201cafuera hacia el centro\u201d y no de \u201carriba hacia abajo\u201d. Por eso es que la gente en las calles a menudo dice \u201ces m\u00e1s de lo mismo\u201d\u2026 \u201ces la misma gata pero revolcada\u201d y es producto de una desconexi\u00f3n profunda entre candidatos, propuestas y praxis.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block; text-align: center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"1904291222\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>En la revisi\u00f3n de las plataformas dif\u00edcilmente encontramos claridad conceptual entre los que significa pol\u00edtica de cambio clim\u00e1tico, energ\u00edas limpias y renovables, desarrollo sustentable y a partir de ello hay ambig\u00fcedad en las acciones propuestas, las cu\u00e1les son breves y carecen de innovaci\u00f3n. Vale la pena poner en reserva y darle el beneficio de la duda a Movimiento Ciudadano que en su plataforma coloca en primer lugar el denominado \u201cUn nuevo trato a la naturaleza\u201d que en diez puntos muy concretos ofrecen una visi\u00f3n clim\u00e1tica del pa\u00eds m\u00e1s congruente.<\/p>\n<p>Si las plataformas en sus escritos no nos dicen aspectos relevantes en cuanto al tema, s\u00ed nos dicen mucho por lo que callan. Por eso cobran especial inter\u00e9s los partidos peque\u00f1os como el PVEM o de reciente creaci\u00f3n como el PES, RSP o FUERZA M\u00c9XICO pues su silencio para asumir posturas frente a temas como el uso del combust\u00f3leo o la transici\u00f3n energ\u00e9tica puede esconder el peso de la balanza entre dos frentes ya conformados en el tema.<\/p>\n<p>Estos debates se han convertido en un examen para quienes acuden como representantes de los partidos, para saber qu\u00e9 tanto conocen al partido que abanderan y al pa\u00eds que quieren gobernar, por supuesto que salen reprobados.<\/p>\n<p>Lo que queda claro es que hay dos frentes conformados para este rubro: MORENA, PT y PVEM cuya postura es defender los programas del ejecutivo federal como \u201cSembrando Vida\u201d, \u201cEl Tren Maya\u201d, #LeydelCombust\u00f3leo, construcci\u00f3n de refiner\u00edas con la asignaci\u00f3n de los presupuestos necesarios para su realizaci\u00f3n a pesar de los costos ambientales, y partidos como PAN, PRI, PRD y MC que buscan integrar un frente que frene estas iniciativas y reorientar el presupuesto hacia otras propuestas (que a\u00fan no logran acordar, es decir, saben que van por la oposici\u00f3n pero a\u00fan les falta ponerse de acuerdo en cu\u00e1les ser\u00e1n sus acciones de respuesta para ser un bloque real de oposici\u00f3n).<\/p>\n<p>Cuando se vota por un candidato o candidata no solo se elige a la persona, sino por el peso que tendr\u00e1 el partido que representa y el bloque al que pertenece ese mismo partido, es un principio en el equilibrio de poderes que le hace falta a este pa\u00eds.<\/p>\n<p>Las \u00fanicas opciones para los ciudadanos son claras: nos informamos sobre las acciones para hacer frente a la emergencia clim\u00e1tica y emitimos un voto razonado o dejamos que alguien m\u00e1s decida en el presente con consecuencias para los pr\u00f3ximos 50 a\u00f1os.<\/p>\n<p>Cada voto es un voto por el clima<\/p>\n<p>@jarumymendez<\/p>\n<h3>El debate referido en el INE:<\/h3>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/y_QHBKYnJf4\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h3>M\u00e1s videos en el canal de Youtube de ELORIENTE.NET:<\/h3>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/88ibYrgo_KI\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"4595267748\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"http:\/\/www.eloriente.net\/home\/2021\/05\/03\/indicio-esmeralda-por-jarumy-mendez\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t\tdata-colorscheme = \"dark\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div>\n\t\t  <style>\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Indicio Esmeralda, por Jarumy M\u00e9ndez El Debate Electoral sobre Medio Ambiente El pasado 26 de abril se llev\u00f3 a cabo el Tercer Debate ante el INE de los partidos pol\u00edticos nacionales en torno al tema de Medio Ambiente y Desarrollo Sustentable. Estos formatos que ha emprendido el INE tienen como objetivo poner a \u201cDebate las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11,71,32,8473,10504,10,20,24,21],"tags":[1187,11824,8475,8557,956],"class_list":["post-64331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colaboradores","category-elecciones","category-entradas","category-jarumy-esmeralda-mendez-reyes","category-las-ultimas-12","category-lo-mas-reciente","category-medio-ambiente","category-mexico-y-el-mundo","category-politica-y-gobierno","tag-debate","tag-debate-ine","tag-indicio-esmeralda","tag-jarumy-mendez","tag-medio-ambiente-2"],"jetpack_featured_media_url":"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2019\/04\/Foto-bosque.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/64331"}],"collection":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/comments?post=64331"}],"version-history":[{"count":1,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/64331\/revisions"}],"predecessor-version":[{"id":64332,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/64331\/revisions\/64332"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media\/56521"}],"wp:attachment":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media?parent=64331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/categories?post=64331"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/tags?post=64331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}