{"id":6547,"date":"2012-12-28T09:30:53","date_gmt":"2012-12-28T15:30:53","guid":{"rendered":"http:\/\/www.eloriente.net\/home\/?p=6547"},"modified":"2012-12-28T08:19:42","modified_gmt":"2012-12-28T14:19:42","slug":"putin-promulga-ley-que-prohibe-a-estadounidenses-adoptar-ninos-rusos","status":"publish","type":"post","link":"http:\/\/www.eloriente.net\/home\/2012\/12\/28\/putin-promulga-ley-que-prohibe-a-estadounidenses-adoptar-ninos-rusos\/","title":{"rendered":"Putin promulga ley que prohibe a estadounidenses adoptar ni\u00f1os rusos"},"content":{"rendered":"<p>eloriente.net<\/p>\n<p>28 de diciembre de 2012<\/p>\n<p>eloriente.net (Oaxaca, Oax.) 28 de diciembre de 2012.- Este viernes 28 de diciembre de 2012, el Presidente de Rusia, Vlad\u00edmir Putin, promulg\u00f3 una ley que prev\u00e9 sanciones contra estadounidenses que hayan vulnerado los derechos de ciudadanos de Rusia y proh\u00edbe las adopciones de ni\u00f1os rusos en EEUU.<\/p>\n<p>De acuerdo a la informaci\u00f3n difundida esta ma\u00f1ana por <a href=\"http:\/\/oncetv-ipn.net\" target=\"_blank\">Once TV<\/a> y diversos medios nacionales e internacionales, la ley aprobada anteriormente por ambas C\u00e1maras parlamentarias, entrar\u00e1 en vigor a partir del 1 de enero de 2013.<\/p>\n<p>A esta ley se le conoce como \u00abley anti Magnitski\u00bb, por ser considerada la respuesta rusa a una normativa aprobada recientemente en Estados Unidos que prev\u00e9 sanciones a funcionarios rusos presuntamente implicados en infracciones de derechos humanos en Rusia.<\/p>\n<p>La Agencia de Informaci\u00f3n Internacional de Rusia <a href=\"http:\/\/sp.rian.ru\" target=\"_blank\">\u00abRIA Novosti\u00bb<\/a>, inform\u00f3 que a la nueva normativa se llama extraoficialmente \u201cley Dima Y\u00e1kovlev\u201d, en homenaje a un ni\u00f1o ruso que muri\u00f3 en EEUU, en 2008, despu\u00e9s de que su padre adoptivo lo dejara encerrado en un coche.<\/p>\n<p>Las ONGs que se dedican a las actividades pol\u00edticas con financiaci\u00f3n desde EEUU o promueven algunos proyectos que amenazan a los intereses de Rusia no podr\u00e1n trabajar en este pa\u00eds, acorde a la nueva ley.<\/p>\n<p>Este medio de comunicaci\u00f3n ruso difundi\u00f3 que paralelamente a esta ley, Putin promulg\u00f3 un decreto para incentivar las adopciones nacionales, en particular, mediante, la agilizaci\u00f3n de los tr\u00e1mites correspondientes y la concesi\u00f3n de privilegios econ\u00f3micos y fiscales a los padres adoptivos.<\/p>\n<p>La \u201cley Dima Y\u00e1kovlev\u201d fue duramente criticada por los sectores liberales en Rusia que la calificaron de pol\u00edtica. De los ni\u00f1os rusos adoptados en 2011, el 31,4% (3.400) fueron a hogares extranjeros y el 68,6% (7.416) se quedaron en Rusia, seg\u00fan las estad\u00edsticas del Ministerio ruso de Educaci\u00f3n. Los estadounidenses adoptaron 956 ni\u00f1os rusos el pasado a\u00f1o.<\/p>\n<p>Diecinueve ni\u00f1os rusos murieron en hogares adoptivos en EEUU a lo largo del \u00faltimo decenio, seg\u00fan la oficina del Defensor del Menor ruso, P\u00e1vel Ast\u00e1jov.<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/12\/imgvladimir-putin4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6548\" title=\"imgvladimir-putin4\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/12\/imgvladimir-putin4.jpg\" alt=\"\" width=\"379\" height=\"298\" srcset=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/12\/imgvladimir-putin4.jpg 379w, http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/12\/imgvladimir-putin4-300x235.jpg 300w\" sizes=\"(max-width: 379px) 100vw, 379px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"http:\/\/www.eloriente.net\/home\/2012\/12\/28\/putin-promulga-ley-que-prohibe-a-estadounidenses-adoptar-ninos-rusos\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t\tdata-colorscheme = \"dark\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div>\n\t\t  <style>\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>eloriente.net 28 de diciembre de 2012 eloriente.net (Oaxaca, Oax.) 28 de diciembre de 2012.- Este viernes 28 de diciembre de 2012, el Presidente de Rusia, Vlad\u00edmir Putin, promulg\u00f3 una ley que prev\u00e9 sanciones contra estadounidenses que hayan vulnerado los derechos de ciudadanos de Rusia y proh\u00edbe las adopciones de ni\u00f1os rusos en EEUU. De acuerdo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32,10,24],"tags":[],"class_list":["post-6547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entradas","category-lo-mas-reciente","category-mexico-y-el-mundo"],"jetpack_featured_media_url":"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/12\/imgvladimir-putin4.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/6547"}],"collection":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/comments?post=6547"}],"version-history":[{"count":1,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/6547\/revisions"}],"predecessor-version":[{"id":6549,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/6547\/revisions\/6549"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media\/6548"}],"wp:attachment":[{"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media?parent=6547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/categories?post=6547"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/tags?post=6547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}