{"id":2170,"date":"2012-08-21T10:05:34","date_gmt":"2012-08-21T16:05:34","guid":{"rendered":"http:\/\/www.eloriente.net\/home\/?p=2170"},"modified":"2012-09-04T01:43:31","modified_gmt":"2012-09-04T07:43:31","slug":"se-pospone-espacio-oaxaca-2012","status":"publish","type":"post","link":"https:\/\/www.eloriente.net\/home\/2012\/08\/21\/se-pospone-espacio-oaxaca-2012\/","title":{"rendered":"Se pospone \u00abEspacio Oaxaca 2012\u00bb"},"content":{"rendered":"<p>eloriente.net\/<a href=\"http:\/\/vinculacion.org\/\" target=\"_blank\">EVAC<\/a><\/p>\n<p>21 de agosto de 2012<\/p>\n<p>eloriente.net(Oaxaca, Oax) 21 de agosto de 2012.- En un Comunicado, Espacio de Vinculaci\u00f3n A.C (EVAC) anunci\u00f3 que Espacio Oaxaca 2012 ser\u00e1 pospuesto hasta el 2013 debido a que no se pueden garantizar las condiciones de seguridad necesarias para llevar a cabo el evento.<\/p>\n<p>EVAC (Espacio de Vinculaci\u00f3n, Asociaci\u00f3n Civil) es una entidad sin fines de lucro que busca vincular a los diferentes sectores de la sociedad a trav\u00e9s de sus diversos eventos para facilitar la comunicaci\u00f3n entre la comunidad acad\u00e9mica, instituciones empresariales y organismos gubernamentales nacionales e internacionales.<\/p>\n<p>En su portal de internet, \u00a0la Asociaci\u00f3n expone que por primera ocasi\u00f3n en diecisiete a\u00f1os el ejercicio anual de EVAC en M\u00e9xico, Espacio, ser\u00e1 pospuesto hasta el a\u00f1o pr\u00f3ximo.<\/p>\n<p>El compromiso de realizaci\u00f3n del evento Espacio en Oaxaca, convenido con el Gobernador Gabino Cu\u00e9, tuvo un cambio de sus fechas originales en marzo, debido a la veda electoral decretada por el Instituto Federal Electoral.<\/p>\n<p>Posteriormente se acord\u00f3 realizar Espacio en el mes de octubre. Sin embargo, en acuerdo con las autoridades del Estado y haciendo una evaluaci\u00f3n de los diversos movimientos sociales en la regi\u00f3n, se decidi\u00f3 posponer el evento hasta que puedan garantizarse las condiciones de seguridad necesarias para la realizaci\u00f3n del mismo.<\/p>\n<p>Por este motivo, Espacio de Vinculaci\u00f3n A.C. decidi\u00f3 dar prioridad a sus actividades en M\u00e9xico, realizando una serie de\u00a0<strong>Di\u00e1logos Necesarios<\/strong>\u00a0que ser\u00e1n transmitidos por diversos medios con la misi\u00f3n de rendir cuenta del momento nacional.<\/p>\n<p>De acuerdo a la informaci\u00f3n anunciada, se convocar\u00e1 a \u00a0un debate entre juventud y los principales actores de procesos nacionales e internacionales en materia de:<\/p>\n<ul>\n<li><strong>Educaci\u00f3n<\/strong>: Linaje del Conocimiento<\/li>\n<li><strong>Econom\u00eda<\/strong>: Igualdad de Posiciones<\/li>\n<li><strong>Sociedad<\/strong>: Juventud efervescente<\/li>\n<li><strong>Cultura<\/strong>: Valor a los recursos<\/li>\n<li><strong>Comunicaci\u00f3n<\/strong>: Mediar, re-mediar, democratizar<\/li>\n<\/ul>\n<p>Los debates se \u00a0efectuar\u00e1n el pr\u00f3ximo 15 al 19 de octubre.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/08\/espacio2012.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-2171\" title=\"espacio2012\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/08\/espacio2012-300x166.jpeg\" alt=\"\" width=\"300\" height=\"166\" srcset=\"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/08\/espacio2012-300x166.jpeg 300w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/08\/espacio2012.jpeg 629w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.eloriente.net\/home\/2012\/08\/21\/se-pospone-espacio-oaxaca-2012\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t\tdata-colorscheme = \"dark\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div>\n\t\t  <style>\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>eloriente.net\/EVAC 21 de agosto de 2012 eloriente.net(Oaxaca, Oax) 21 de agosto de 2012.- En un Comunicado, Espacio de Vinculaci\u00f3n A.C (EVAC) anunci\u00f3 que Espacio Oaxaca 2012 ser\u00e1 pospuesto hasta el 2013 debido a que no se pueden garantizar las condiciones de seguridad necesarias para llevar a cabo el evento. EVAC (Espacio de Vinculaci\u00f3n, Asociaci\u00f3n Civil) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32,10,31],"tags":[],"class_list":["post-2170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entradas","category-lo-mas-reciente","category-principal"],"jetpack_featured_media_url":"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/08\/espacio2012.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/2170"}],"collection":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/comments?post=2170"}],"version-history":[{"count":3,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/2170\/revisions"}],"predecessor-version":[{"id":2585,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/2170\/revisions\/2585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media\/2171"}],"wp:attachment":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media?parent=2170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/categories?post=2170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/tags?post=2170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}