{"id":43217,"date":"2016-04-19T12:11:46","date_gmt":"2016-04-19T18:11:46","guid":{"rendered":"http:\/\/www.eloriente.net\/home\/?p=43217"},"modified":"2016-04-19T15:25:00","modified_gmt":"2016-04-19T21:25:00","slug":"letras-saben-los-mexicanos-cuando-se-celebra-el-dia-mundial-del-libro","status":"publish","type":"post","link":"https:\/\/www.eloriente.net\/home\/2016\/04\/19\/letras-saben-los-mexicanos-cuando-se-celebra-el-dia-mundial-del-libro\/","title":{"rendered":"LETRAS: \u00bfSaben los mexicanos cu\u00e1ndo se celebra el D\u00eda Mundial del Libro?"},"content":{"rendered":"<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- BANNER ELORIENTE INCRUSTADO NOTAS --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 300px; height: 250px;\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"7974633627\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/p>\n<p>&nbsp;<\/p>\n<p>(www.eloriente.net, M\u00e9xico, a 19 de abril de 2016, por Valery L\u00f3pez).-\u00a0Los libros han sido parte importante del desarrollo de la humanidad, desde textos religiosos hasta cient\u00edficos han contribuido a la formaci\u00f3n de conocimiento e identidad en muchas sociedades.<\/p>\n<p>El <strong>23 de abril<\/strong> fue designado por la Conferencia General de la UNESCO como el <strong>D\u00eda Mundial del Libro y del Derecho de Autor<\/strong>, la Conferencia eligi\u00f3 esa fecha porque, de acuerdo a la UNESCO, un 23 de abril de 1616 fallecieron <strong>Miguel de Cervantes<\/strong>,<strong> William Shakespeare<\/strong> e<strong> Inca Garcilaso de la Vega<\/strong>. La fecha tambi\u00e9n coincide con el nacimiento o la muerte de otros autores prominentes como <strong>Maurice Druon<\/strong>, <strong>Haldor K.Laxness<\/strong>, <strong>Vladimir Nabokov<\/strong>, <strong>Josep Pla<\/strong> y <strong>Manuel Mej\u00eda Vallejo<\/strong>.<\/p>\n<p>A 4 d\u00edas de la celebraci\u00f3n mundial del libro surge una pregunta interesante \u00bfqu\u00e9 tanto nos relacionamos los mexicanos con la literatura? <a href=\"http:\/\/www.gii360.com.mx\/detalleEncuesta.php?idc=200\" target=\"_blank\">El Grupo Impacto<strong> Gii360<\/strong><\/a> se dio a la tarea de realizar una encuesta sobre dicho tema y estos fueron los resultados.<\/p>\n<p>La encuesta abre con la pregunta <strong>\u00ab\u00bfUsted sabe cu\u00e1ndo se celebra el D\u00eda Mundial del Libro?\u00bb<\/strong> A lo que un <strong>96% respondi\u00f3 que no sab\u00eda la fecha<\/strong> en la que se realiza dicha celebraci\u00f3n.<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.38.png\" rel=\"attachment wp-att-43221\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-43221\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.38.png\" alt=\"Captura de pantalla 2016-04-19 a las 12.53.38\" width=\"600\" height=\"473\" srcset=\"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.38.png 1618w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.38-300x237.png 300w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.38-768x606.png 768w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.38-1024x808.png 1024w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>\u00ab\u00bfUsted con cual de siguientes palabras asocia m\u00e1s a los libros?\u00bb<\/strong>\u00a0fue la segunda pregunta, la respuesta que obtuvo el porcentaje m\u00e1s alto fue <strong>Cultura con un 73%<\/strong> seguida de I<strong>nformaci\u00f3n y Entretenimiento con un 12 y 10 por ciento respectivamente<\/strong>.<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.58.png\" rel=\"attachment wp-att-43222\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-43222\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.58.png\" alt=\"Captura de pantalla 2016-04-19 a las 12.53.58\" width=\"600\" height=\"474\" srcset=\"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.58.png 1616w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.58-300x237.png 300w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.58-768x606.png 768w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.53.58-1024x809.png 1024w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- BANNER PEQUE\u00d1O PARA ENTRENOTAS EL ORIENTE --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 468px; height: 60px;\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"4953536424\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/p>\n<p>Otra pregunta interesante que encontramos en esta encuesta fue <strong>\u00ab\u00bfUsted acostumbra leer?\u00bb<\/strong> En donde el <strong>73% dijo que s\u00ed<\/strong> lo hace mientras que el <strong>19% dijo que no<\/strong> lo acostumbra.<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.24.png\" rel=\"attachment wp-att-43223\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-43223\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.24.png\" alt=\"Captura de pantalla 2016-04-19 a las 12.54.24\" width=\"600\" height=\"470\" srcset=\"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.24.png 1624w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.24-300x235.png 300w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.24-768x602.png 768w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.24-1024x802.png 1024w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>\u00danicamente al grupo que respondi\u00f3 de manera afirmativa se les pregunt\u00f3 <strong>\u00ab\u00bfcu\u00e1ntos libros ley\u00f3 usted en el \u00faltimo a\u00f1o?\u00bb<\/strong> El <strong>21% dijo que 3<\/strong>, el 1<strong>9% dijo que s\u00f3lo fueron dos libros<\/strong> los que leyeron. Sorprendentemente el <strong>14% de las personas<\/strong> que dijeron que acostumbraban leer<strong> no tocaron un solo libro en el \u00faltimo a\u00f1o<\/strong>.<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.34.png\" rel=\"attachment wp-att-43224\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-43224\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.34.png\" alt=\"Captura de pantalla 2016-04-19 a las 12.54.34\" width=\"600\" height=\"482\" srcset=\"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.34.png 1622w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.34-300x241.png 300w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.34-768x616.png 768w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Captura-de-pantalla-2016-04-19-a-las-12.54.34-1024x822.png 1024w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Por \u00faltimo se le pregunt\u00f3 al grupo que no acostumbra leer \u00bfcu\u00e1l es el principal motivo por el que no lo hacen? Siendo \u00abFalta de tiempo\u00bb la principal raz\u00f3n por la que los mexicanos no leen.<\/p>\n<p>Este \u00faltimo resultado nos hizo recordar la <strong><a href=\"http:\/\/www.eloriente.net\/home\/2015\/11\/09\/prefieren-mexicanos-leer-por-entretenimiento\/\" target=\"_blank\">Encuesta Nacional de Lectura<\/a><\/strong> publicada el a\u00f1o pasado, en la que se mostraba que 80% de los mexicanos no leen por falta de tiempo.<\/p>\n<p>En el siguiente <strong><a href=\"http:\/\/www.gii360.com.mx\/detalleEncuesta.php?idc=200\" target=\"_blank\">enlace<\/a><\/strong> podr\u00e1n consultar de manera \u00edntegra la encuesta publicada por Gii360<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Libros-por-@CCAC-North-Library.jpg\" rel=\"attachment wp-att-43226\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-43226\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Libros-por-@CCAC-North-Library.jpg\" alt=\"Libros por @CCAC North Library\" width=\"600\" height=\"399\" srcset=\"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Libros-por-@CCAC-North-Library.jpg 3008w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Libros-por-@CCAC-North-Library-300x199.jpg 300w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Libros-por-@CCAC-North-Library-768x511.jpg 768w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Libros-por-@CCAC-North-Library-1024x681.jpg 1024w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>OTRAS ENTRADAS<\/strong><\/p>\n<div class=\"featuredpost\">\n<div class=\"flow_hide\">\n<h2 class=\"posttitle bigposttitle\"><a title=\"Enlace Permanente a LETRAS: Fernando del Paso recibe el Premio Cervantes\" href=\"http:\/\/www.eloriente.net\/home\/2016\/04\/18\/letras-fernando-del-paso-recibe-el-premio-cervantes\/\" rel=\"bookmark\">LETRAS: Fernando del Paso recibe el Premio Cervantes<\/a><\/h2>\n<\/div>\n<p>eloriente.net\/Secretar\u00eda de Cultura 18 de abril de 2016* (El pr\u00f3ximo 23 de abril, el mexicano recibir\u00e1 el prestigioso Premio Cervantes) Fernando del Paso naci\u00f3 el 1 de abril\u2026<\/p>\n<p class=\"postmeta\"><span class=\"meta_date\">abril 18, 2016<\/span><\/p>\n<div class=\"toolbar-social\"><\/div>\n<\/div>\n<div class=\"featuredpost\">\n<div class=\"flow_hide\">\n<p><a href=\"http:\/\/www.eloriente.net\/home\/2016\/04\/18\/felicidad-abre-nuevo-reto-de-meditacion-de-deepak-chopra-e-ismael-cala\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"alignleft\" title=\"FELICIDAD: Abre Nuevo Reto de Meditaci\u00f3n de Deepak Chopra e Ismael Cala\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/themes\/city-desk\/timthumb.php?src=http%3A%2F%2Fwww.eloriente.net%2Fhome%2Fwp-content%2Fuploads%2F2016%2F04%2F21-DIAS-CHOPRA.jpg&amp;q=90&amp;w=70&amp;h=45&amp;zc=1\" alt=\"FELICIDAD: Abre Nuevo Reto de Meditaci\u00f3n de Deepak Chopra e Ismael Cala\" \/><\/a><\/p>\n<h2 class=\"posttitle \"><a title=\"Enlace Permanente a FELICIDAD: Abre Nuevo Reto de Meditaci\u00f3n de Deepak Chopra e Ismael Cala\" href=\"http:\/\/www.eloriente.net\/home\/2016\/04\/18\/felicidad-abre-nuevo-reto-de-meditacion-de-deepak-chopra-e-ismael-cala\/\" rel=\"bookmark\">FELICIDAD: Abre Nuevo Reto de Meditaci\u00f3n de Deepak Chopra e Ismael Cala<\/a><\/h2>\n<\/div>\n<p>eloriente.net 18 de abril de 2016 MIAMI, 18 de abril de 2016 \/PRNewswire\/ \u2014 Reg\u00edstrate gratis en http:\/\/ismaelcala.com\/meditacion El nuevo Reto de Meditaci\u00f3n de 21 D\u00edas, del Chopra\u2026<\/p>\n<p class=\"postmeta\"><span class=\"meta_date\">abril 18, 2016<\/span><\/p>\n<div class=\"toolbar-social\"><\/div>\n<\/div>\n<div class=\"featuredpost\">\n<div class=\"flow_hide\">\n<p><a href=\"http:\/\/www.eloriente.net\/home\/2016\/04\/18\/videocolumna-la-gente-en-situacion-de-pobreza-decidira-resultado-electoral-karina-baron\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"alignleft\" title=\"VIDEOCOLUMNA: La gente en situaci\u00f3n de pobreza decidir\u00e1 resultado electoral: Karina Bar\u00f3n\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/themes\/city-desk\/timthumb.php?src=http%3A%2F%2Fwww.eloriente.net%2Fhome%2Fwp-content%2Fuploads%2F2016%2F04%2Fkb-18-de-abril-1-e1461018529135.jpg&amp;q=90&amp;w=70&amp;h=45&amp;zc=1\" alt=\"VIDEOCOLUMNA: La gente en situaci\u00f3n de pobreza decidir\u00e1 resultado electoral: Karina Bar\u00f3n\" \/><\/a><\/p>\n<h2 class=\"posttitle \"><a title=\"Enlace Permanente a VIDEOCOLUMNA: La gente en situaci\u00f3n de pobreza decidir\u00e1 resultado electoral: Karina Bar\u00f3n\" href=\"http:\/\/www.eloriente.net\/home\/2016\/04\/18\/videocolumna-la-gente-en-situacion-de-pobreza-decidira-resultado-electoral-karina-baron\/\" rel=\"bookmark\">VIDEOCOLUMNA: La gente en situaci\u00f3n de pobreza decidir\u00e1 resultado electoral: Karina Bar\u00f3n<\/a><\/h2>\n<\/div>\n<p>eloriente.net 18 de abril de 2016 Para ver y leer m\u00e1s opiniones, da click en la siguiente imagen: Share\u2026<\/p>\n<p class=\"postmeta\"><span class=\"meta_date\">abril 18, 2016<\/span><\/p>\n<\/div>\n\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.eloriente.net\/home\/2016\/04\/19\/letras-saben-los-mexicanos-cuando-se-celebra-el-dia-mundial-del-libro\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t\tdata-colorscheme = \"dark\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div>\n\t\t  <style>\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>&nbsp; (www.eloriente.net, M\u00e9xico, a 19 de abril de 2016, por Valery L\u00f3pez).-\u00a0Los libros han sido parte importante del desarrollo de la humanidad, desde textos religiosos hasta cient\u00edficos han contribuido a la formaci\u00f3n de conocimiento e identidad en muchas sociedades. El 23 de abril fue designado por la Conferencia General de la UNESCO como el D\u00eda [&hellip;]<\/p>\n","protected":false},"author":44,"featured_media":43226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18,32,35,3153,10],"tags":[6372,432,553,6373,2101,297,1040,141,419],"class_list":["post-43217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion-y-cultura","category-entradas","category-secciones-oriente","category-letras-educacion-y-cultura","category-lo-mas-reciente","tag-dia-mundial-del-libro","tag-encuesta","tag-estudio","tag-gii360","tag-letras","tag-literatura","tag-mexicanos","tag-mexico","tag-unesco"],"jetpack_featured_media_url":"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2016\/04\/Libros-por-@CCAC-North-Library.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/43217"}],"collection":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/comments?post=43217"}],"version-history":[{"count":2,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/43217\/revisions"}],"predecessor-version":[{"id":43228,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/43217\/revisions\/43228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media\/43226"}],"wp:attachment":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media?parent=43217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/categories?post=43217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/tags?post=43217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}