{"id":4391,"date":"2012-10-24T17:09:20","date_gmt":"2012-10-24T23:09:20","guid":{"rendered":"http:\/\/www.eloriente.net\/home\/?p=4391"},"modified":"2013-05-24T08:09:01","modified_gmt":"2013-05-24T14:09:01","slug":"cambio-social-y-cultura","status":"publish","type":"post","link":"https:\/\/www.eloriente.net\/home\/2012\/10\/24\/cambio-social-y-cultura\/","title":{"rendered":"Cambio Social y Cultural"},"content":{"rendered":"<p style=\"text-align: right;\">Por: Juan Pablo Vasconcelos<\/p>\n<p>Oaxaca es hoy un lugar complejo, interesante y propicio para vivir. Lo es por las mismas razones por las cuales pudiera pensarse lo contrario: que es un lugar l\u00f3brego, confuso y sin salida. Es propicio por sus problemas, sus contradicciones, su obsesi\u00f3n por permanecer en el atraso con tal de defender una dignidad ancestral, misma que nadie ha visto pero todo mundo asume e imagina.<\/p>\n<p>Es decir, lo es porque en la dificultad hay oportunidad, porque de la confusi\u00f3n sobreviene la revelaci\u00f3n, porque durante la enfermedad se piensa en los remedios. Y es un privilegio ser parte de todo ello.<\/p>\n<p>Las mejores historias son las que se escriben desde la adversidad, cuando el reto es may\u00fasculo y los recursos poco aprovechados; all\u00ed, el personaje debe sobreponerse incluso a s\u00ed mismo para decidir realizar su viaje, su desaf\u00edo, y alcanzar su destino.<\/p>\n<p>En este caso, creo leer que nuestra historia se encuentra justo en el momento de esa determinaci\u00f3n, donde todos los factores nos est\u00e1n orillando a tomar decisiones para cambiar, transformarnos, reconstruirnos. Como en las narraciones, todos los factores se confabulan para que los personajes se embarquen en la aventura.<\/p>\n<p>Y creo que estamos en condiciones de hacerlo, pero debemos intentarlo a profundidad, no con el discurso vacuo, el asociacionismo pasajero o la mentira. De hecho, este es propiamente el riesgo inherente a toda historia: el enga\u00f1o, cuya consecuencia desoladora es despojar para siempre de esperanza a los ciudadanos, los inmoviliza, los silencia.<\/p>\n<p>El enga\u00f1o somete la confianza, provoca la incredulidad y anula el consenso posible.<\/p>\n<p>Sin embargo, creo tambi\u00e9n que estos riesgos est\u00e1n lo suficientemente identificados. En el fondo, sabemos qui\u00e9nes son los que practican estos actos y sus razones. Pero nos hace falta dar un paso hacia adelante, un paso que cambie definitivamente los modales y las reglas del juego, una transformaci\u00f3n cultural que derrumbe los paradigmas por los cuales nos hemos conducido y que han provocado el letargo autodestructivo que vivimos.<\/p>\n<p>Dice Garc\u00eda Canclini que \u201cla cultura popular no puede ser entendida como \u2018expresi\u00f3n\u2019 de la personalidad de un pueblo, al modo del idealismo, porque tal personalidad no existe como entidad a priori, metaf\u00edsica, sino que se forma en la interacci\u00f3n de las relaciones sociales\u201d.<\/p>\n<p>En este sentido, si bien ser\u00eda ingenuo, grandilocuente y falto de contexto pretender construir algo llamado \u201ccultura\u201d, s\u00ed es posible conducir, crear condiciones y poner \u00e9nfasis en un determinado perfil de situaci\u00f3n, que propicie el cambio que perseguimos. Y de all\u00ed, (1) poner al centro de la discusi\u00f3n el tema cultural, (2) en la conciencia com\u00fan, (3) en un n\u00facleo axiol\u00f3gico compartido, y (4) en un proyecto simb\u00f3lico claro que traduzca lo que somos pero sobre todo lo que pretendemos ser tanto social como individualmente.<\/p>\n<p>Aqu\u00ed tambi\u00e9n sabemos los riesgos y los enemigos: los determinismos y las teor\u00edas de la cat\u00e1strofe. Los \u201cas\u00ed somos\u201d. Evitemos ser presa de los determinismos: la vida nos demuestra cada d\u00eda que todo cambia y que nada es permanente; ni tampoco del pesimismo, esa costumbre propia de los temerosos.<\/p>\n<p>Sin esta perspectiva cultural, amplia e integral, todos los esfuerzos parecen incompletos porque lo son; palian s\u00f3lo necesidades moment\u00e1neas, inmediatistas. Ayudan a cumplir indicadores y subir escalafones en los \u00edndices. Pero lo que no hacen, es crear ciudadanos m\u00e1s proclives a desarrollar libremente su personalidad, sus talentos y posibilidades. Personas con los horizontes abiertos, responsables de su libertad, solidarios, compasivos, felices.<\/p>\n<p>Una perspectiva de reconstrucci\u00f3n cultural que haga v\u00e1lido el orgullo que, decimos, sentimos por lo nuestro.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/10\/Aniversario4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4392\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/10\/Aniversario4-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/10\/Aniversario4-300x199.jpg 300w, https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/10\/Aniversario4.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.eloriente.net\/home\/2012\/10\/24\/cambio-social-y-cultura\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t\tdata-colorscheme = \"dark\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div>\n\t\t  <style>\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Por: Juan Pablo Vasconcelos Oaxaca es hoy un lugar complejo, interesante y propicio para vivir. Lo es por las mismas razones por las cuales pudiera pensarse lo contrario: que es un lugar l\u00f3brego, confuso y sin salida. Es propicio por sus problemas, sus contradicciones, su obsesi\u00f3n por permanecer en el atraso con tal de defender [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":4392,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32,54,10],"tags":[],"class_list":["post-4391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entradas","category-juan-pablo-vasconcelos","category-lo-mas-reciente"],"jetpack_featured_media_url":"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/10\/Aniversario4.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/4391"}],"collection":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/comments?post=4391"}],"version-history":[{"count":2,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/4391\/revisions"}],"predecessor-version":[{"id":12249,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/4391\/revisions\/12249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media\/4392"}],"wp:attachment":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media?parent=4391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/categories?post=4391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/tags?post=4391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}