{"id":6152,"date":"2012-12-13T15:14:05","date_gmt":"2012-12-13T21:14:05","guid":{"rendered":"http:\/\/www.eloriente.net\/home\/?p=6152"},"modified":"2012-12-13T18:05:10","modified_gmt":"2012-12-14T00:05:10","slug":"futbol-profesional-en-oaxaca","status":"publish","type":"post","link":"https:\/\/www.eloriente.net\/home\/2012\/12\/13\/futbol-profesional-en-oaxaca\/","title":{"rendered":"Futbol profesional en Oaxaca"},"content":{"rendered":"<p>eloriente.net<\/p>\n<p>13 de diciembre de 2012<\/p>\n<p>Imposible sustraernos de la noticia de que el futbol, en liga de ascenso, llega a Oaxaca. Imposible, porque en @El_Oriente hemos insistido en que el deporte debe ser un \u00e1mbito prioritario para las personas, la sociedad y el gobierno. De hecho, creemos en el deporte como ese pu\u00f1o concentrado de valores que pueden ayudarnos, eventualmente, a vivir.<\/p>\n<p>Esa forma en que los atletas se sobreponen a las adversidades, la forma en que una fuerza imposible los impulsa terminar la carrera o a alcanzar velocidades ins\u00f3litas, la solidaridad del trabajo en equipo, son s\u00f3lo algunos de los valores del deporte que tambi\u00e9n funcionan en la vida.<\/p>\n<p>As\u00ed que la llegada del futbol profesional a Oaxaca, de nueva cuenta, abre posibilidades de distinto tipo: econ\u00f3mico, empresarial, social. Pero la que creemos m\u00e1s importante es que puede significar un aliciente para miles de aficionados y jugadores en la b\u00fasqueda de s\u00edmbolos en los cuales desbocar su \u00edmpetu, juventud y \u00e1nimo.<\/p>\n<p>En Oaxaca requerimos invertir en el \u00e1nimo. Y entre otras cosas ello se logra invirtiendo en s\u00edmbolos. Suena parad\u00f3jico que un intangible pueda nutrirse de otro intangible. Pero a menudo no son necesarias becas o apoyos econ\u00f3micos para que las personas nos sintamos mejor, integrados\u00a0 a la comunidad, tripulantes del mismo barco.<\/p>\n<p>Ejemplos puede haber muchos en el pa\u00eds. Casos en que el equipo de futbol se vuelve un referente en la identidad del lugar y sus pobladores. De alguna manera, les otorga una bandera. Claro, una bandera aut\u00e9ntica cargada de emotividad, pasi\u00f3n, gusto por el juego.<\/p>\n<p>As\u00ed que el proceso de construcci\u00f3n del proyecto debe ser muy cuidadoso en estos aspectos identitarios.<\/p>\n<p>Por mencionar uno de ellos: es com\u00fan que este tipo de equipos no incluyan jugadores de Oaxaca. En efecto, se contratan jugadores extranjeros, t\u00e9cnicos y entrenadores de otros lugares de la rep\u00fablica, pero la gente local no encuentra rostros propios en esos equipos. Ello encuentra su justificaci\u00f3n econ\u00f3mica, pero una justificaci\u00f3n social. Y creemos que el caso, nuestra situaci\u00f3n, nuestra circunstancia, amerita que los j\u00f3venes de Oaxaca sean considerados. De esta forma puede ahorrarse mucho tiempo en la apropiaci\u00f3n del equipo y se tratar\u00eda de una inyecci\u00f3n de \u00e1nimo social indiscutible.<\/p>\n<p>Oaxaque\u00f1os para el equipo de Oaxaca es la premisa en este sentido, por las razones planteadas.<\/p>\n<p>Saludos con gusto, inter\u00e9s y pasi\u00f3n este proyecto que, de acuerdo, a la informaci\u00f3n disponible estar\u00eda comenzado hostilidades a mediados de 2013 pero que estar\u00eda construyendo nuevo estado a partir de enero. Lo consideramos necesario, valioso y elocuente. Estamos en presencia de lo que puede ser un s\u00edmbolo de gran trascendencia social e impacto comunitario.<\/p>\n<p><a href=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/12\/Algunos-derechos-reservados-por-rahego-bal\u00f3n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6153\" title=\"OLYMPUS DIGITAL CAMERA\" src=\"http:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/12\/Algunos-derechos-reservados-por-rahego-bal\u00f3n-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/><\/a>Foto: <a href=\"http:\/\/www.flickr.com\/photos\/rahego\/\" target=\"_blank\">rahego<\/a>, <a href=\"http:\/\/creativecommons.org\/licenses\/by\/2.0\/\" target=\"_blank\">Algunos derechos reservados.<\/a><\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.eloriente.net\/home\/2012\/12\/13\/futbol-profesional-en-oaxaca\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t\tdata-colorscheme = \"dark\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div>\n\t\t  <style>\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>eloriente.net 13 de diciembre de 2012 Imposible sustraernos de la noticia de que el futbol, en liga de ascenso, llega a Oaxaca. Imposible, porque en @El_Oriente hemos insistido en que el deporte debe ser un \u00e1mbito prioritario para las personas, la sociedad y el gobierno. De hecho, creemos en el deporte como ese pu\u00f1o concentrado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6153,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,32],"tags":[],"class_list":["post-6152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editorial","category-entradas"],"jetpack_featured_media_url":"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2012\/12\/Algunos-derechos-reservados-por-rahego-balo\u0301n.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/6152"}],"collection":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/comments?post=6152"}],"version-history":[{"count":2,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/6152\/revisions"}],"predecessor-version":[{"id":6159,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/6152\/revisions\/6159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media\/6153"}],"wp:attachment":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media?parent=6152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/categories?post=6152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/tags?post=6152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}