{"id":63740,"date":"2020-12-12T12:29:16","date_gmt":"2020-12-12T18:29:16","guid":{"rendered":"http:\/\/www.eloriente.net\/home\/?p=63740"},"modified":"2020-12-12T12:29:16","modified_gmt":"2020-12-12T18:29:16","slug":"aniversario-de-licenciatura-en-entrenamiento-deportivo","status":"publish","type":"post","link":"https:\/\/www.eloriente.net\/home\/2020\/12\/12\/aniversario-de-licenciatura-en-entrenamiento-deportivo\/","title":{"rendered":"Aniversario de Licenciatura en Entrenamiento Deportivo"},"content":{"rendered":"<p>\u201cCelebro el inicio del 4to. Congreso Internacional de Ciencias Aplicadas al Deporte, muestra del extraordinario desarrollo que ha tenido la Facultad de Cultura F\u00edsica y Deporte (FCFD), la cual inici\u00f3 con una licenciatura y ahora ofrece un posgrado y capacitaciones constantes\u201d, expres\u00f3 el Rector de la M\u00e1xima Casa de Estudios, Eduardo Bautista Mart\u00ednez.<\/p>\n<p>Lo anterior en el acto inaugural realizado de manera virtual, como parte de las actividades conmemorativas del XIV Aniversario de la Licenciatura en Entrenamiento Deportivo (LED).<\/p>\n<p>\u201cReconozco las acciones colectivas que hoy convocan a expertas y expertos de diversas partes del mundo, es la oportunidad de generar di\u00e1logos y debates para observar y robustecer la formaci\u00f3n deportiva desde una perspectiva integral\u201d, enfatiz\u00f3.<\/p>\n<p>De esta manera nuestra Casa de Estudios contribuye con soluciones y alternativas, \u201cseguimos trabajando con una planta docente capacitada, asumimos con responsabilidad los retos derivados de la contingencia sanitaria y mantenemos nuestros procesos formativos con esfuerzos coordinados\u201d, concluy\u00f3.<\/p>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block; text-align: center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1136171134853753\" data-ad-slot=\"1904291222\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><br \/>\nPor su parte, el Director de la Facultad, Adolfo Demetrio G\u00f3mez Hern\u00e1ndez, refiri\u00f3 que \u201cla UABJO tiene objetivos firmes para generar profesionales con una visi\u00f3n integral, mismos que son compartidos por esta Unidad Acad\u00e9mica para atender los diferentes sectores sociales, principalmente con quienes promueven y difunden el deporte\u201d.<\/p>\n<p>Agreg\u00f3, que el encuentro acad\u00e9mico se realizar\u00e1 durante tres d\u00edas, bajo 3 ejes tem\u00e1ticos: cultura f\u00edsica, deporte y salud, con 10 conferencias magistrales, 9 talleres y 3 charlas, con la participaci\u00f3n de especialistas de pa\u00edses como Francia, Rumania, Cuba y M\u00e9xico.<\/p>\n<p>G\u00f3mez Hern\u00e1ndez, agradeci\u00f3 el apoyo de la Rector\u00eda para la realizaci\u00f3n de esta actividad, que abona a los indicadores de calidad que forman parte de los ejes trazados en el Plan Institucional de Desarrollo (PID 2016-2020) de la actual administraci\u00f3n.<\/p>\n<p>En este evento estuvieron presentes, el Secretario Acad\u00e9mico, Javier Mart\u00ednez Mar\u00edn, el Coordinador de Posgrado, Luis Abel Solano Santiago; el Director del Instituto de Ciencias de la Educaci\u00f3n (ICE), H\u00e9ctor Aguilar Aguilar y el Director de la Facultad de Derecho y Ciencias Sociales (FDCS), Carlos Perezcampos Mayoral.<\/p>\n<p>As\u00ed como docentes, personal administrativo y la comunidad participante en las actividades programadas, las cuales son gratuitas y se transmiten en la p\u00e1gina de la Facultad <a href=\"http:\/\/www.facebook.com\/ECFyD\/\">www.facebook.com\/ECFyD\/<\/a><\/p>\n\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"https:\/\/www.eloriente.net\/home\/2020\/12\/12\/aniversario-de-licenciatura-en-entrenamiento-deportivo\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t\tdata-colorscheme = \"dark\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div>\n\t\t  <style>\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 100% !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>\u201cCelebro el inicio del 4to. Congreso Internacional de Ciencias Aplicadas al Deporte, muestra del extraordinario desarrollo que ha tenido la Facultad de Cultura F\u00edsica y Deporte (FCFD), la cual inici\u00f3 con una licenciatura y ahora ofrece un posgrado y capacitaciones constantes\u201d, expres\u00f3 el Rector de la M\u00e1xima Casa de Estudios, Eduardo Bautista Mart\u00ednez. Lo anterior [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":63741,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15,32,63,35,10504,10,464,8677],"tags":[451,8941,4389,182],"class_list":["post-63740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-entradas","category-estados","category-secciones-oriente","category-las-ultimas-12","category-lo-mas-reciente","category-oaxaca-estados","category-uabjo","tag-deportes-2","tag-eduardo-bautista","tag-licenciatura-en-entrenamiento-deportivo","tag-uabjo"],"jetpack_featured_media_url":"https:\/\/www.eloriente.net\/home\/wp-content\/uploads\/2020\/12\/Recto-Eduardo-Bautista-UABJO-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/63740"}],"collection":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/comments?post=63740"}],"version-history":[{"count":1,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/63740\/revisions"}],"predecessor-version":[{"id":63742,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/posts\/63740\/revisions\/63742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media\/63741"}],"wp:attachment":[{"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/media?parent=63740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/categories?post=63740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eloriente.net\/home\/wp-json\/wp\/v2\/tags?post=63740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}